{"id":4066,"date":"2023-11-08T09:30:40","date_gmt":"2023-11-08T06:30:40","guid":{"rendered":"https:\/\/medcare.com.tr\/fr\/?post_type=portfolio&#038;p=4066"},"modified":"2024-10-15T17:26:42","modified_gmt":"2024-10-15T14:26:42","slug":"blouse-chirurgicale-renforcee-sterile","status":"publish","type":"portfolio","link":"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-renforcee-sterile\/","title":{"rendered":"Blouse Chirurgicale Renforc\u00e9e St\u00e9rile"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-138txag-9cc5aa55fbf10deb2e6dc9d3d8472367 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4066'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-10tjcko-2079263d1d165d7b9aba94b1fca76f1f\">\n.flex_column.av-10tjcko-2079263d1d165d7b9aba94b1fca76f1f{\nwidth:38.2%;\n}\n<\/style>\n<div  class='flex_column av-10tjcko-2079263d1d165d7b9aba94b1fca76f1f av_two_fifth  avia-builder-el-1  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-loiiwh1k-6dff86636cd8b0ce6e3a62c1d8da6624\">\n#top .avia-gallery.av-loiiwh1k-6dff86636cd8b0ce6e3a62c1d8da6624 .avia-gallery-thumb a{\nwidth:14.2857%;\n}\n<\/style>\n<div  class='avia-gallery av-loiiwh1k-6dff86636cd8b0ce6e3a62c1d8da6624 avia_animate_when_visible  avia-builder-el-2  avia-builder-el-no-sibling  avia_lazyload av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows hover-effect av-control-hidden avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-renforcee-sterile\/\"><a class='avia-gallery-big fakeLightbox lightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\"  data-onclick='1' title='' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" class=\"wp-image-4068 avia-img-lazy-loading-not-4068\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/span><\/a><div class='avia-gallery-thumb'><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg' class='first_thumb lightbox ' data-onclick='1' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4068 avia-img-lazy-loading-not-4068\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4068 avia-img-lazy-loading-4068\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg' class='lightbox ' data-onclick='2' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4069 avia-img-lazy-loading-not-4069\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4069 avia-img-lazy-loading-4069\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-2-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg' class='lightbox ' data-onclick='3' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4070 avia-img-lazy-loading-not-4070\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4070 avia-img-lazy-loading-4070\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-3-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg' class='lightbox ' data-onclick='4' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4071 avia-img-lazy-loading-not-4071\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4071 avia-img-lazy-loading-4071\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-4-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg' class='lightbox ' data-onclick='5' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4072 avia-img-lazy-loading-not-4072\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4072 avia-img-lazy-loading-4072\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-5-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg' class='lightbox ' data-onclick='6' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4073 avia-img-lazy-loading-not-4073\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4073 avia-img-lazy-loading-4073\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-6-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7-470x705.jpg 470w\" data-sizes=\"(max-width: 667px) 100vw, 667px\" data-rel='gallery-1' data-prev-img='https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg' class='lightbox ' data-onclick='7' title=''  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" class=\"wp-image-4074 avia-img-lazy-loading-not-4074\"   src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg\" width=\"667\" height=\"1000\"  title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><div class='big-prev-fake'><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4074 avia-img-lazy-loading-4074\"  width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg\" title='' alt='' srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-7-470x705.jpg 470w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><\/a><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ze7kig-2b92a75ee860bac202809df2b4ec32a9\">\n.flex_column.av-ze7kig-2b92a75ee860bac202809df2b4ec32a9{\nwidth:58.8%;\nmargin-left:3%;\n}\n<\/style>\n<div  class='flex_column av-ze7kig-2b92a75ee860bac202809df2b4ec32a9 av_three_fifth  avia-builder-el-3  el_after_av_two_fifth  avia-builder-el-last  flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a\">\n#top .av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a{\npadding-bottom:10px;\ncolor:#134094;\nfont-size:24px;\n}\nbody .av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a .av-special-heading-tag{\nfont-size:24px;\n}\n.av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a .special-heading-inner-border{\nborder-color:#134094;\n}\n.av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a .av-subheading{\nfont-size:16px;\ncolor:#65a8dd;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  id=\"girisbaslik\"  class='av-special-heading av-loihtyzd-042d8155bd7d9a3eed94cfd499b9c65a av-special-heading-h3 custom-color-heading blockquote modern-quote  avia-builder-el-4  el_before_av_table  avia-builder-el-first  girisbaslik girisbaslik av-inherit-size'><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Blouse Chirurgicale Renforc\u00e9e St\u00e9rile<\/h3><div class='av_custom_color av-subheading av-subheading_below'><p>R\u00c9F.N\u00b0\u00a0:20.001.01-20.002.01-20.003.01-20.004.01-20.005.01-20.006.01<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div class='avia-data-table-wrap av-av_table-e389ce42c4b648166e325b04dde3e313 avia_responsive_table avia-table-1'><table  id=\"uruntable1\"  class='avia-table avia-data-table avia_pricing_default  avia-builder-el-5  el_after_av_heading  el_before_av_textblock  uruntable1'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Table\" ><tbody><tr class='avia-heading-row'><th class=''>R\u00c9F.N\u00b0\u00a0:<\/th><th class=''>CONTENU DU PACK<\/th><th class=''>DIMENSION<\/th><th class=''>COULEUR<\/th><\/tr><tr class=''><td class=''>20.001.01<\/td><td class=''>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile + 1 Essuie-mains<\/td><td class=''>S<\/td><td class=''>Bleue<\/td><\/tr><tr class=''><td class=''>20.002.01<\/td><td class=''>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile + 1 Essuie-mains<\/td><td class=''>M<\/td><td class=''>Bleue<\/td><\/tr><tr class=''><td class=''>20.003.01<\/td><td class=''>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile + 1 Essuie-mains<\/td><td class=''>L<\/td><td class=''>Bleue<\/td><\/tr><tr class=''><td class=''>20.004.01<\/td><td class=''>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile + 1 Essuie-mains<\/td><td class=''>XL<\/td><td class=''>Bleue<\/td><\/tr><tr class=''><td class=''>20.005.01<\/td><td class=''>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile + 1 Essuie-mains<\/td><td class=''>XXL<\/td><td class=''>Bleue<\/td><\/tr><tr class=''><td class=''>20.006.01<\/td><td class=''>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile + 1 Essuie-mains<\/td><td class=''>XXXL<\/td><td class=''>Bleue<\/td><\/tr><\/tbody><\/table><\/div><style type='text\/css'>.avia-table-1 td:nth-of-type(1):before { content: 'R\u00c9F.N\u00b0\u00a0:'; } .avia-table-1 td:nth-of-type(2):before { content: 'CONTENU DU PACK'; } .avia-table-1 td:nth-of-type(3):before { content: 'DIMENSION'; } .avia-table-1 td:nth-of-type(4):before { content: 'COULEUR'; } <\/style><br \/>\n<section  class='av_textblock_section av-loihypf7-bb58a34f5c42cd2ca6a01f852dc5950d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>\u2022 Blouses chirurgicales\/d&#8217;isolement standard st\u00e9riles\/non st\u00e9riles<br \/>\n\u2022 Toutes les blouses peuvent \u00eatre livr\u00e9es en couture Overlock ou en soudage par ultrasons<br \/>\n\u2022 Selon le choix des clients, les blouses st\u00e9riles peuvent \u00eatre livr\u00e9es telles quelles ou avec 1 essuie-mains ou 2 essuie-mains et un film de st\u00e9rilisation.<br \/>\n\u2022 St\u00e9rilisation \u00e0 l&#8217;EO<br \/>\n\u2022 Pliage m\u00e9dical<br \/>\n\u2022 Fabriqu\u00e9 en tissus non tiss\u00e9s (SSMMS, SMS, PP+PE Biflex, Triplex, Repellent Triplex, SS Spunbond)<\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-x9ystk-d8c0ba2fed39fbc326907ae4bdd99c89 main_color avia-section-default avia-no-border-styling  avia-builder-el-7  el_after_av_section  el_before_av_heading  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4066'><div class='entry-content-wrapper clearfix'>\n<div id='av-masonry-1' class='av-masonry av-vscxig-6013ea39fbc316f6e20a0fca8899381c noHover av-flex-size av-no-gap av-hover-overlay-active av-masonry-animation-active av-masonry-col-5 av-caption-always av-caption-style- av-masonry-gallery ' data-post_id=\"4066\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security-705x470.jpg 705w\" data-sizes=\"(max-width: 900px) 100vw, 900px\"  aria-label=\"image Soudure par ultrasons pour une s\u00e9curit\u00e9 renforc\u00e9e\"  id='av-masonry-1-item-4050' data-av-masonry-item='4050' class='av-masonry-entry isotope-item post-4050 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Soudure par ultrasons pour une s\u00e9curit\u00e9 renforc\u00e9e\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'   ><img decoding=\"async\" width=\"900\" height=\"600\" class=\"wp-image-4050 avia-img-lazy-loading-not-4050\"  src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security.jpg\" title=\"Soudure par ultrasons pour une s\u00e9curit\u00e9 renforc\u00e9e\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welding-for-enhanced-security-705x470.jpg 705w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Soudure par ultrasons pour une s\u00e9curit\u00e9 renforc\u00e9e<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck-705x470.jpg 705w\" data-sizes=\"(max-width: 900px) 100vw, 900px\"  aria-label=\"image Bande Velcro pour une meilleure adh\u00e9rence autour du cou\"  id='av-masonry-1-item-4051' data-av-masonry-item='4051' class='av-masonry-entry isotope-item post-4051 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Bande Velcro pour une meilleure adh\u00e9rence autour du cou\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'   ><img decoding=\"async\" width=\"900\" height=\"600\" class=\"wp-image-4051 avia-img-lazy-loading-not-4051\"  src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck.jpg\" title=\"Bande Velcro pour une meilleure adh\u00e9rence autour du cou\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Velcro-tape-for-better-grip-around-the-neck-705x470.jpg 705w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Bande Velcro pour une meilleure adh\u00e9rence autour du cou<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security-705x470.jpg 705w\" data-sizes=\"(max-width: 900px) 100vw, 900px\"  aria-label=\"image Ceintures soud\u00e9es par ultrasons pour une s\u00e9curit\u00e9 maximale\"  id='av-masonry-1-item-4052' data-av-masonry-item='4052' class='av-masonry-entry isotope-item post-4052 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Ceintures soud\u00e9es par ultrasons pour une s\u00e9curit\u00e9 maximale\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'   ><img decoding=\"async\" width=\"900\" height=\"600\" class=\"wp-image-4052 avia-img-lazy-loading-not-4052\"  src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security.jpg\" title=\"Ceintures soud\u00e9es par ultrasons pour une s\u00e9curit\u00e9 maximale\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Ultrasonic-welded-belts-for-maximum-security-705x470.jpg 705w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Ceintures soud\u00e9es par ultrasons pour une s\u00e9curit\u00e9 maximale<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff-705x470.jpg 705w\" data-sizes=\"(max-width: 900px) 100vw, 900px\"  aria-label=\"image Manchette \u00e9lastique de 8 cm de long\"  id='av-masonry-1-item-4053' data-av-masonry-item='4053' class='av-masonry-entry isotope-item post-4053 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Manchette \u00e9lastique de 8 cm de long\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'   ><img decoding=\"async\" width=\"900\" height=\"600\" class=\"wp-image-4053 avia-img-lazy-loading-not-4053\"  src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff.jpg\" title=\"Manchette \u00e9lastique de 8 cm de long\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/8-cm-long-elastic-cuff-705x470.jpg 705w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Manchette \u00e9lastique de 8 cm de long<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security.jpg\" data-srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security-705x470.jpg 705w\" data-sizes=\"(max-width: 900px) 100vw, 900px\"  aria-label=\"image Attache de ceinture \u00e0 4 lacets pour une meilleure s\u00e9curit\u00e9\"  id='av-masonry-1-item-4054' data-av-masonry-item='4054' class='av-masonry-entry isotope-item post-4054 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Attache de ceinture \u00e0 4 lacets pour une meilleure s\u00e9curit\u00e9\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'   ><img decoding=\"async\" width=\"900\" height=\"600\" class=\"wp-image-4054 avia-img-lazy-loading-not-4054\"  src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security.jpg\" title=\"Attache de ceinture \u00e0 4 lacets pour une meilleure s\u00e9curit\u00e9\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security.jpg 900w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security-300x200.jpg 300w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security-768x512.jpg 768w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/4-Laced-belt-tie-for-better-security-705x470.jpg 705w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Attache de ceinture \u00e0 4 lacets pour une meilleure s\u00e9curit\u00e9<\/h3><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_2'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4066'><div class='entry-content-wrapper clearfix'><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4a3a7m-21e679e34e1e165fea8a6370242d565f\">\n#top .av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f{\npadding-bottom:10px;\ncolor:#134094;\nfont-size:24px;\n}\nbody .av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f .av-special-heading-tag{\nfont-size:24px;\n}\n.av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f .special-heading-inner-border{\nborder-color:#134094;\n}\n.av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f .av-subheading{\nfont-size:16px;\ncolor:#65a8dd;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-4a3a7m-21e679e34e1e165fea8a6370242d565f .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  id=\"girisbaslik\"  class='av-special-heading av-4a3a7m-21e679e34e1e165fea8a6370242d565f av-special-heading-h3 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-9  el_after_av_section  el_before_av_portfolio  avia-builder-el-no-sibling  girisbaslik girisbaslik av-inherit-size'><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Nos autres produits <\/h3><div class='av_custom_color av-subheading av-subheading_below'><p>Blouses Chirurgicales St\u00e9riles<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  id=\"av-sc-portfolio-1\"  class=' grid-sort-container isotope   no_margin-container with-title-container grid-total-odd grid-col-6 grid-links-' data-portfolio-id='1'><div data-ajax-id='4088' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-4088 grid-entry-overview grid-loop-1 grid-parity-odd  sterile-surgical-gowns_sort  av_one_sixth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-durologie\/\" title='Blouse D&#8217;Urologie'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Urology-Gown-1.jpg\" class=\"wp-image-4090 avia-img-lazy-loading-not-4090 attachment-no scaling size-no scaling wp-post-image\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Urology-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Urology-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Urology-Gown-1-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-durologie\/' title='Blouse D&#8217;Urologie'>Blouse D&#8217;Urologie<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='4008' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-4008 grid-entry-overview grid-loop-2 grid-parity-even  sterile-surgical-gowns_sort  av_one_sixth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-protection-complete-sterile\/\" title='Blouse Protection Compl\u00e8te St\u00e9rile'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/kapak-gorseli.jpg\" class=\"wp-image-4057 avia-img-lazy-loading-not-4057 attachment-no scaling size-no scaling wp-post-image\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/kapak-gorseli.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/kapak-gorseli-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/kapak-gorseli-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-protection-complete-sterile\/' title='Blouse Protection Compl\u00e8te St\u00e9rile'>Blouse Protection Compl\u00e8te St\u00e9rile<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='4029' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-4029 grid-entry-overview grid-loop-3 grid-parity-odd  sterile-surgical-gowns_sort  av_one_sixth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-laminee-sterile\/\" title='Blouse Chirurgicale Lamin\u00e9e St\u00e9rile'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Laminated-Surgical-Gown-1.jpg\" class=\"wp-image-4031 avia-img-lazy-loading-not-4031 attachment-no scaling size-no scaling wp-post-image\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Laminated-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Laminated-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Laminated-Surgical-Gown-1-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-laminee-sterile\/' title='Blouse Chirurgicale Lamin\u00e9e St\u00e9rile'>Blouse Chirurgicale Lamin\u00e9e St\u00e9rile<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='4066' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-4066 grid-entry-overview grid-loop-4 grid-parity-even  sterile-surgical-gowns_sort  av_one_sixth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-renforcee-sterile\/\" title='Blouse Chirurgicale Renforc\u00e9e St\u00e9rile'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg\" class=\"wp-image-4068 avia-img-lazy-loading-not-4068 attachment-no scaling size-no scaling wp-post-image\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Reinforced-Surgical-Gown-1-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-renforcee-sterile\/' title='Blouse Chirurgicale Renforc\u00e9e St\u00e9rile'>Blouse Chirurgicale Renforc\u00e9e St\u00e9rile<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='4076' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-4076 grid-entry-overview grid-loop-5 grid-parity-odd  post-entry-last  sterile-surgical-gowns_sort  av_one_sixth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-standard-sterile\/\" title='Blouse Chirurgicale Standard St\u00e9rile'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Standard-Surgical-Gown-1.jpg\" class=\"wp-image-4080 avia-img-lazy-loading-not-4080 attachment-no scaling size-no scaling wp-post-image\" alt=\"\" srcset=\"https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Standard-Surgical-Gown-1.jpg 667w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Standard-Surgical-Gown-1-200x300.jpg 200w, https:\/\/medcare.com.tr\/fr\/wp-content\/uploads\/2023\/11\/Standard-Surgical-Gown-1-470x705.jpg 470w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/medcare.com.tr\/fr\/portfolio-item\/blouse-chirurgicale-standard-sterile\/' title='Blouse Chirurgicale Standard St\u00e9rile'>Blouse Chirurgicale Standard St\u00e9rile<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4068,"comment_status":"open","ping_status":"closed","template":"","tags":[],"portfolio_entries":[24],"class_list":["post-4066","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-sterile-surgical-gowns"],"_links":{"self":[{"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/portfolio\/4066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/comments?post=4066"}],"version-history":[{"count":3,"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/portfolio\/4066\/revisions"}],"predecessor-version":[{"id":5106,"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/portfolio\/4066\/revisions\/5106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/media\/4068"}],"wp:attachment":[{"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/media?parent=4066"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/tags?post=4066"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/medcare.com.tr\/fr\/wp-json\/wp\/v2\/portfolio_entries?post=4066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}